{"id":2606,"date":"2016-08-22T17:40:34","date_gmt":"2016-08-22T15:40:34","guid":{"rendered":"http:\/\/www.prosunt.si\/?page_id=2606"},"modified":"2022-12-13T16:26:36","modified_gmt":"2022-12-13T15:26:36","slug":"e-narocilnica-za-podjetje-napake-pri-zdravstveni-obravnavi-pacientov","status":"publish","type":"page","link":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/e-narocilnica-za-podjetje-napake-pri-zdravstveni-obravnavi-pacientov\/","title":{"rendered":"E-Naro\u010dilnica za podjetje &#8220;Napake pri zdravstveni obravnavi pacientov&#8221;"},"content":{"rendered":"<div class=\"et_d4_element et_pb_section et_pb_section_0  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_0  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_0  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\">Prosimo izpolnite naro\u010dilnico.\u00a0Po prejemu naro\u010dila vam po\u0161ljemo ra\u010dun in knjigo.<\/p>\n<p><script type=\"text\/javascript\">var gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,initializeOnLoaded:function(o){gform.domLoaded&&gform.scriptsLoaded?o():!gform.domLoaded&&gform.scriptsLoaded?window.addEventListener(\"DOMContentLoaded\",o):document.addEventListener(\"gform_main_scripts_loaded\",o)},hooks:{action:{},filter:{}},addAction:function(o,n,r,t){gform.addHook(\"action\",o,n,r,t)},addFilter:function(o,n,r,t){gform.addHook(\"filter\",o,n,r,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,n){gform.removeHook(\"action\",o,n)},removeFilter:function(o,n,r){gform.removeHook(\"filter\",o,n,r)},addHook:function(o,n,r,t,i){null==gform.hooks[o][n]&&(gform.hooks[o][n]=[]);var e=gform.hooks[o][n];null==i&&(i=n+\"_\"+e.length),gform.hooks[o][n].push({tag:i,callable:r,priority:t=null==t?10:t})},doHook:function(n,o,r){var t;if(r=Array.prototype.slice.call(r,1),null!=gform.hooks[n][o]&&((o=gform.hooks[n][o]).sort(function(o,n){return o.priority-n.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==n?t.apply(null,r):r[0]=t.apply(null,r)})),\"filter\"==n)return r[0]},removeHook:function(o,n,t,i){var r;null!=gform.hooks[o][n]&&(r=(r=gform.hooks[o][n]).filter(function(o,n,r){return!!(null!=i&&i!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][n]=r)}});<\/script>\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_13' ><style>#gform_wrapper_13[data-form-index=\"0\"].gform-theme,[data-parent-form=\"13_0\"]{--gform-theme-color-primary: #204ce5;--gform-theme-color-primary-rgb: 32, 76, 229;--gform-theme-color-primary-contrast: #fff;--gform-theme-color-primary-contrast-rgb: 255, 255, 255;--gform-theme-color-primary-darker: #001AB3;--gform-theme-color-primary-lighter: #527EFF;--gform-theme-color-secondary: #fff;--gform-theme-color-secondary-rgb: 255, 255, 255;--gform-theme-color-secondary-contrast: #112337;--gform-theme-color-secondary-contrast-rgb: 17, 35, 55;--gform-theme-color-secondary-darker: #F5F5F5;--gform-theme-color-secondary-lighter: #FFFFFF;--gform-theme-color-outside-control-light: rgba(17, 35, 55, 0.1);--gform-theme-color-outside-control-light-rgb: 17, 35, 55;--gform-theme-color-outside-control-light-darker: rgba(104, 110, 119, 0.35);--gform-theme-color-outside-control-light-lighter: #F5F5F5;--gform-theme-color-outside-control-dark: #585e6a;--gform-theme-color-outside-control-dark-rgb: 88, 94, 106;--gform-theme-color-outside-control-dark-darker: #112337;--gform-theme-color-outside-control-dark-lighter: rgba(17, 35, 55, 0.65);--gform-theme-color-inside-control: #fff;--gform-theme-color-inside-control-rgb: 255, 255, 255;--gform-theme-color-inside-control-contrast: #112337;--gform-theme-color-inside-control-contrast-rgb: 17, 35, 55;--gform-theme-color-inside-control-darker: #F5F5F5;--gform-theme-color-inside-control-lighter: #FFFFFF;--gform-theme-color-inside-control-primary: #204ce5;--gform-theme-color-inside-control-primary-rgb: 32, 76, 229;--gform-theme-color-inside-control-primary-contrast: #fff;--gform-theme-color-inside-control-primary-contrast-rgb: 255, 255, 255;--gform-theme-color-inside-control-primary-darker: #001AB3;--gform-theme-color-inside-control-primary-lighter: #527EFF;--gform-theme-color-inside-control-light: rgba(17, 35, 55, 0.1);--gform-theme-color-inside-control-light-rgb: 17, 35, 55;--gform-theme-color-inside-control-light-darker: rgba(104, 110, 119, 0.35);--gform-theme-color-inside-control-light-lighter: #F5F5F5;--gform-theme-color-inside-control-dark: #585e6a;--gform-theme-color-inside-control-dark-rgb: 88, 94, 106;--gform-theme-color-inside-control-dark-darker: #112337;--gform-theme-color-inside-control-dark-lighter: rgba(17, 35, 55, 0.65);--gform-theme-border-radius: 3px;--gform-theme-font-size-secondary: 14px;--gform-theme-font-size-tertiary: 13px;--gform-theme-icon-control-number: url(\"data:image\/svg+xml,%3Csvg width='8' height='14' viewBox='0 0 8 14' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M4 0C4.26522 5.96046e-08 4.51957 0.105357 4.70711 0.292893L7.70711 3.29289C8.09763 3.68342 8.09763 4.31658 7.70711 4.70711C7.31658 5.09763 6.68342 5.09763 6.29289 4.70711L4 2.41421L1.70711 4.70711C1.31658 5.09763 0.683417 5.09763 0.292893 4.70711C-0.0976311 4.31658 -0.097631 3.68342 0.292893 3.29289L3.29289 0.292893C3.48043 0.105357 3.73478 0 4 0ZM0.292893 9.29289C0.683417 8.90237 1.31658 8.90237 1.70711 9.29289L4 11.5858L6.29289 9.29289C6.68342 8.90237 7.31658 8.90237 7.70711 9.29289C8.09763 9.68342 8.09763 10.3166 7.70711 10.7071L4.70711 13.7071C4.31658 14.0976 3.68342 14.0976 3.29289 13.7071L0.292893 10.7071C-0.0976311 10.3166 -0.0976311 9.68342 0.292893 9.29289Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gform-theme-icon-control-select: url(\"data:image\/svg+xml,%3Csvg width='10' height='6' viewBox='0 0 10 6' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M0.292893 0.292893C0.683417 -0.097631 1.31658 -0.097631 1.70711 0.292893L5 3.58579L8.29289 0.292893C8.68342 -0.0976311 9.31658 -0.0976311 9.70711 0.292893C10.0976 0.683417 10.0976 1.31658 9.70711 1.70711L5.70711 5.70711C5.31658 6.09763 4.68342 6.09763 4.29289 5.70711L0.292893 1.70711C-0.0976311 1.31658 -0.0976311 0.683418 0.292893 0.292893Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gform-theme-icon-control-search: url(\"data:image\/svg+xml,%3Csvg version='1.1' xmlns='http:\/\/www.w3.org\/2000\/svg' width='640' height='640'%3E%3Cpath d='M256 128c-70.692 0-128 57.308-128 128 0 70.691 57.308 128 128 128 70.691 0 128-57.309 128-128 0-70.692-57.309-128-128-128zM64 256c0-106.039 85.961-192 192-192s192 85.961 192 192c0 41.466-13.146 79.863-35.498 111.248l154.125 154.125c12.496 12.496 12.496 32.758 0 45.254s-32.758 12.496-45.254 0L367.248 412.502C335.862 434.854 297.467 448 256 448c-106.039 0-192-85.962-192-192z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gform-theme-control-border-color: #686e77;--gform-theme-control-size: var(--gform-theme-control-size-md);--gform-theme-control-label-color-primary: #112337;--gform-theme-control-label-color-secondary: #112337;--gform-theme-control-choice-size: var(--gform-theme-control-choice-size-md);--gform-theme-control-checkbox-check-size: var(--gform-theme-control-checkbox-check-size-md);--gform-theme-control-radio-check-size: var(--gform-theme-control-radio-check-size-md);--gform-theme-control-button-font-size: var(--gform-theme-control-button-font-size-md);--gform-theme-control-button-padding-inline: var(--gform-theme-control-button-padding-inline-md);--gform-theme-control-button-size: var(--gform-theme-control-button-size-md);--gform-theme-control-button-border-color-secondary: #686e77;--gform-theme-control-file-button-background-color-hover: #EBEBEB;--gform-theme-field-page-steps-number-color: rgba(17, 35, 55, 0.8);}<\/style>\n                        <div class='gform_heading'>\n                            <h3 class=\"gform_title\">E-Naro\u010dilnica za ustanovo \"Napake pri zdravstveni obravnavi pacientov\"<\/h3>\n                        <\/div><form method='post' enctype='multipart\/form-data'  id='gform_13'  action='\/prosunt-2-2-2\/wp-json\/wp\/v2\/pages\/2606' data-formid='13' novalidate>\n                        <div class='gform-body gform_body'><ul id='gform_fields_13' class='gform_fields top_label form_sublabel_below description_below'><li id=\"field_13_1\"  class=\"gfield gfield--type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below gfield_visibility_visible\"  data-js-reload=\"field_13_1\"><label class='gfield_label gform-field-label' for='input_13_1' >Naziv organizacije<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_13_1' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/> <\/div><\/li><li id=\"field_13_24\"  class=\"gfield gfield--type-text gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below gfield_visibility_visible\"  data-js-reload=\"field_13_24\"><label class='gfield_label gform-field-label' for='input_13_24' >Ime in priimek odgovorne osebe<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_24' id='input_13_24' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/> <\/div><\/li><li id=\"field_13_20\"  class=\"gfield gfield--type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below gfield_visibility_visible\"  data-js-reload=\"field_13_20\"><label class='gfield_label gform-field-label' for='input_13_20' >Dav\u010dna \u0161tevilka<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_20' id='input_13_20' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/> <\/div><\/li><li id=\"field_13_3\"  class=\"gfield gfield--type-radio gfield--type-choice gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below gfield_visibility_visible\"  data-js-reload=\"field_13_3\"><label class='gfield_label gform-field-label'  >Zavezanec za DDV<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_radio'><ul class='gfield_radio' id='input_13_3'>\n\t\t\t<li class='gchoice gchoice_13_3_0'>\n\t\t\t\t<input name='input_3' type='radio' value='Da'  id='choice_13_3_0'    \/>\n\t\t\t\t<label for='choice_13_3_0' id='label_13_3_0' class='gform-field-label gform-field-label--type-inline'>Da<\/label>\n\t\t\t<\/li>\n\t\t\t<li class='gchoice gchoice_13_3_1'>\n\t\t\t\t<input name='input_3' type='radio' value='Ne'  id='choice_13_3_1'    \/>\n\t\t\t\t<label for='choice_13_3_1' id='label_13_3_1' class='gform-field-label gform-field-label--type-inline'>Ne<\/label>\n\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_13_7\"  class=\"gfield gfield--type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below gfield_visibility_visible\"  data-js-reload=\"field_13_7\"><label class='gfield_label gform-field-label' for='input_13_7' >Naslov<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_7' id='input_13_7' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/> <\/div><\/li><li id=\"field_13_18\"  class=\"gfield gfield--type-text gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below gfield_visibility_visible\"  data-js-reload=\"field_13_18\"><label class='gfield_label gform-field-label' for='input_13_18' >Po\u0161ta in po\u0161tna \u0161t.<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_18' id='input_13_18' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/> <\/div><\/li><li id=\"field_13_10\"  class=\"gfield gfield--type-email gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below gfield_visibility_visible\"  data-js-reload=\"field_13_10\"><label class='gfield_label gform-field-label' for='input_13_10' >Elektronski naslov<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_10' id='input_13_10' type='email' value='' class='medium'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/li><li id=\"field_13_11\"  class=\"gfield gfield--type-text gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below gfield_visibility_visible\"  data-js-reload=\"field_13_11\"><label class='gfield_label gform-field-label' for='input_13_11' >Telefon<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_11' id='input_13_11' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/> <\/div><\/li><li id=\"field_13_25\"  class=\"gfield gfield--type-product gfield--input-type-singleproduct gf_left_half gfield_price gfield_price_13_25 gfield_product_13_25 field_sublabel_below gfield--has-description field_description_below gfield_visibility_visible\"  data-js-reload=\"field_13_25\"><label class='gfield_label gform-field-label gfield_label_before_complex' for='input_13_25_1' >Knjiga: napake pri zdravstveni obravnavi. Cena  104,00 \u20ac<\/label><div class='ginput_container ginput_container_singleproduct'>\n\t\t\t\t\t<input type='hidden' name='input_25.1' value='Knjiga: napake pri zdravstveni obravnavi. Cena  104,00 \u20ac' class='gform_hidden' \/>\n\t\t\t\t\t\n\t\t\t\t\t\t<label for='ginput_price_13_25_2' class='gform-field-label gform-field-label--type-sub-large ginput_product_price_label'>Price:<\/label>\n\t\t\t\t\t\t<input type='text' readonly name='input_25.2' class='ginput_product_price gform-text-input-reset' id='ginput_base_price_13_25' value='104,00 &#8364;' aria-describedby=\"gfield_description_13_25\" \/>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div><div class='gfield_description' id='gfield_description_13_25'>Cena vsebuje DDV. Po\u0161tnina se zara\u010duna posebej.<\/div><\/li><li id=\"field_13_26\"  class=\"gfield gfield--type-quantity gfield--input-type-number gf_right_half gfield_price gfield_price_13_25 gfield_quantity gfield_quantity_13_25 gfield_contains_required field_sublabel_below gfield--no-description field_description_below gfield_visibility_visible\"  data-js-reload=\"field_13_26\"><label class='gfield_label gform-field-label' for='input_13_26' >Koli\u010dina<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_number'><input name='input_26' id='input_13_26' type='number' step='any'   value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"  \/><\/div><\/li><li id=\"field_13_27\"  class=\"gfield gfield--type-total gf_right_half gfield_price gfield_price_13_ gfield_total gfield_total_13_ field_sublabel_below gfield--no-description field_description_below gfield_visibility_visible\"  aria-atomic=\"true\" aria-live=\"polite\" data-js-reload=\"field_13_27\"><label class='gfield_label gform-field-label' for='input_13_27' >Skupaj<\/label><div class='ginput_container ginput_container_total'>\n\t\t\t\t\t\t\t<span class='ginput_total ginput_total_13'>0,00 &#8364;<\/span>\n\t\t\t\t\t\t\t<input type='hidden' name='input_27' id='input_13_27' class='gform_hidden'\/>\n\t\t\t\t\t\t<\/div><\/li><li id=\"field_13_28\"  class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below gfield_visibility_visible\"  data-js-reload=\"field_13_28\"><label class='gfield_label gform-field-label' for='input_13_28' >Email<\/label><div class='ginput_container'><input name='input_28' id='input_13_28' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_13_28'>This field is for validation purposes and should be left unchanged.<\/div><\/li><\/ul><\/div>\n        <div class='gform_footer top_label'> <input type='submit' id='gform_submit_button_13' class='gform_button button' value='Po\u0161lji'  onclick='if(window[\"gf_submitting_13\"]){return false;}  if( !jQuery(\"#gform_13\")[0].checkValidity || jQuery(\"#gform_13\")[0].checkValidity()){window[\"gf_submitting_13\"]=true;}  ' onkeypress='if( event.keyCode == 13 ){ if(window[\"gf_submitting_13\"]){return false;} if( !jQuery(\"#gform_13\")[0].checkValidity || jQuery(\"#gform_13\")[0].checkValidity()){window[\"gf_submitting_13\"]=true;}  jQuery(\"#gform_13\").trigger(\"submit\",[true]); }' \/> \n            <input type='hidden' class='gform_hidden' name='is_submit_13' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='13' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_13' value='WyJ7XCIyNS4xXCI6XCJhZTU1MDA3NTUyZjNiMDRhYTNiNTk0YzE1NTQwYTNlNFwiLFwiMjUuMlwiOlwiMmM1MzMyYjdlMjJjNTI2NTE0NmFkODE1ZTQ1YjgyODlcIn0iLCJlNjAxMjVkN2RiYjRmYjg2NzhiMmYxMjI4ZDhhYjg0ZiJd' \/>\n            <input type='hidden' class='gform_hidden' name='gform_target_page_number_13' id='gform_target_page_number_13' value='0' \/>\n            <input type='hidden' class='gform_hidden' name='gform_source_page_number_13' id='gform_source_page_number_13' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"ak_\"><label>&#916;<textarea name=\"ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"ak_js\" value=\"165\"\/><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n\/* ]]> *\/\n<\/script>\n<\/p><\/form>\n                        <\/div><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 13, 'https:\/\/www.prosunt.si\/content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_13').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_13');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_13').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_13').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_13').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_13').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_13').val();gformInitSpinner( 13, 'https:\/\/www.prosunt.si\/content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [13, current_page]);window['gf_submitting_13'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}setTimeout(function(){jQuery('#gform_wrapper_13').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [13]);window['gf_submitting_13'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_13').text());}, 50);}else{jQuery('#gform_13').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger('gform_post_render', [13, current_page]);gform.utils.trigger({ event: 'gform\/postRender', native: false, data: { formId: 13, currentPage: current_page } });} );} ); \n\/* ]]> *\/\n<\/script>\n<\/p>\n<p>&nbsp;<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_1  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_1  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p><span style=\"font-size: 20px;\"><strong>Pla\u010dilo po predra\u010dunu s polo\u017enico - za fizi\u010dne in pravne osebe<\/strong><\/span><\/p>\n<p><span style=\"font-size: 16px;\">Ko publikacijo naro\u010dite, vam po elektronski po\u0161ti\u00a0 po\u0161ljemo predra\u010dun. Predra\u010dun poravnate s polo\u017enico prek spletne banke ali prek katerekoli banke ali po\u0161te v Sloveniji. Publikacijo vam po\u0161ljemo po po\u0161ti, ko prejmemo obvestilo o pla\u010dilu s strani banke ali s strani kupca (ko poravnate predra\u010dun, nas o pla\u010dilu obvestite na na\u0161 elektronski naslov\u00a0<a href=\"mailto:info@prosunt.si\">info@prosunt.si<\/a>, na\u00a0tak na\u010din bo naro\u010dena publikacija veliko hitreje pri vas). S pla\u010dilom po predra\u010dunu se izognete pla\u010dilu provizije po\u0161te Slovenije, \u010de se odlo\u010dite za gotovinsko pla\u010dilo ob dostavi Po\u0161te Slovenije.<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><strong>Namen:<\/strong> Naro\u010dilo publikacije. <strong>\u0160tevilka ra\u010duna(IBAN):<\/strong>SI56 6100 0002 2845 884<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u00a0<strong>Sklic (referenca):<\/strong> SI00 78925231.<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><strong>Koda namena:<\/strong> GDSV<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><strong>Banka:<\/strong> Delavska hranilnica<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><strong>BIC:<\/strong> HDELSI22<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><strong>Naslov: <\/strong>Prosunt d.o.o., Blejska cesta 13, Zasip, 4260, Bled<\/span><\/p>\n<p>&nbsp;<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img loading=\"lazy\" decoding=\"async\" width=\"674\" height=\"767\" src=\"https:\/\/www.prosunt.si\/content\/uploads\/2018\/10\/SAGV-Platnice-2.png\" alt=\"\" title=\"\" srcset=\"https:\/\/www.prosunt.si\/content\/uploads\/2018\/10\/SAGV-Platnice-2.png 674w, https:\/\/www.prosunt.si\/content\/uploads\/2018\/10\/SAGV-Platnice-2-300x341.png 300w, https:\/\/www.prosunt.si\/content\/uploads\/2018\/10\/SAGV-Platnice-2-264x300.png 264w, https:\/\/www.prosunt.si\/content\/uploads\/2018\/10\/SAGV-Platnice-2-500x569.png 500w\" sizes=\"(max-width: 674px) 100vw, 674px\" class=\"wp-image-220119\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-template-blank.php","meta":{"_crdt_document":"","_et_pb_use_builder":"on","_et_pb_old_content":"<p>[gravityform id=\"13\" title=\"false\" description=\"false\"]<\/p><p>Tukaj si lahko ogledate<a href=\"https:\/\/www.prosunt.si\/obvestilo-o-zasebnosti\/\"> Obvestilo o zasebnosti<\/a>.<\/p>","_et_gb_content_width":"","footnotes":""},"class_list":["post-2606","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>E-Naro\u010dilnica za podjetje &quot;Napake pri zdravstveni obravnavi pacientov&quot; - https:\/\/www.prosunt.si\/prosunt-2-2-2<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.prosunt.si\/prosunt-2-2-2\/e-narocilnica-za-podjetje-napake-pri-zdravstveni-obravnavi-pacientov\/\" \/>\n<meta property=\"og:locale\" content=\"sl_SI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"E-Naro\u010dilnica za podjetje &quot;Napake pri zdravstveni obravnavi pacientov&quot; - https:\/\/www.prosunt.si\/prosunt-2-2-2\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.prosunt.si\/prosunt-2-2-2\/e-narocilnica-za-podjetje-napake-pri-zdravstveni-obravnavi-pacientov\/\" \/>\n<meta property=\"og:site_name\" content=\"https:\/\/www.prosunt.si\/prosunt-2-2-2\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-13T15:26:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.prosunt.si\\\/prosunt-2-2-2\\\/e-narocilnica-za-podjetje-napake-pri-zdravstveni-obravnavi-pacientov\\\/\",\"url\":\"https:\\\/\\\/www.prosunt.si\\\/prosunt-2-2-2\\\/e-narocilnica-za-podjetje-napake-pri-zdravstveni-obravnavi-pacientov\\\/\",\"name\":\"E-Naro\u010dilnica za podjetje \\\"Napake pri zdravstveni obravnavi pacientov\\\" - https:\\\/\\\/www.prosunt.si\\\/prosunt-2-2-2\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.prosunt.si\\\/prosunt-2-2-2\\\/#website\"},\"datePublished\":\"2016-08-22T15:40:34+00:00\",\"dateModified\":\"2022-12-13T15:26:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.prosunt.si\\\/prosunt-2-2-2\\\/e-narocilnica-za-podjetje-napake-pri-zdravstveni-obravnavi-pacientov\\\/#breadcrumb\"},\"inLanguage\":\"sl-SI\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.prosunt.si\\\/prosunt-2-2-2\\\/e-narocilnica-za-podjetje-napake-pri-zdravstveni-obravnavi-pacientov\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.prosunt.si\\\/prosunt-2-2-2\\\/e-narocilnica-za-podjetje-napake-pri-zdravstveni-obravnavi-pacientov\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.prosunt.si\\\/prosunt-2-2-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E-Naro\u010dilnica za podjetje &#8220;Napake pri zdravstveni obravnavi pacientov&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.prosunt.si\\\/prosunt-2-2-2\\\/#website\",\"url\":\"https:\\\/\\\/www.prosunt.si\\\/prosunt-2-2-2\\\/\",\"name\":\"https:\\\/\\\/www.prosunt.si\\\/prosunt-2-2-2\",\"description\":\"Usposabljanje varnost pacientov kakovost\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.prosunt.si\\\/prosunt-2-2-2\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sl-SI\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"E-Naro\u010dilnica za podjetje \"Napake pri zdravstveni obravnavi pacientov\" - https:\/\/www.prosunt.si\/prosunt-2-2-2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/e-narocilnica-za-podjetje-napake-pri-zdravstveni-obravnavi-pacientov\/","og_locale":"sl_SI","og_type":"article","og_title":"E-Naro\u010dilnica za podjetje \"Napake pri zdravstveni obravnavi pacientov\" - https:\/\/www.prosunt.si\/prosunt-2-2-2","og_url":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/e-narocilnica-za-podjetje-napake-pri-zdravstveni-obravnavi-pacientov\/","og_site_name":"https:\/\/www.prosunt.si\/prosunt-2-2-2","article_modified_time":"2022-12-13T15:26:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/e-narocilnica-za-podjetje-napake-pri-zdravstveni-obravnavi-pacientov\/","url":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/e-narocilnica-za-podjetje-napake-pri-zdravstveni-obravnavi-pacientov\/","name":"E-Naro\u010dilnica za podjetje \"Napake pri zdravstveni obravnavi pacientov\" - https:\/\/www.prosunt.si\/prosunt-2-2-2","isPartOf":{"@id":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/#website"},"datePublished":"2016-08-22T15:40:34+00:00","dateModified":"2022-12-13T15:26:36+00:00","breadcrumb":{"@id":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/e-narocilnica-za-podjetje-napake-pri-zdravstveni-obravnavi-pacientov\/#breadcrumb"},"inLanguage":"sl-SI","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.prosunt.si\/prosunt-2-2-2\/e-narocilnica-za-podjetje-napake-pri-zdravstveni-obravnavi-pacientov\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/e-narocilnica-za-podjetje-napake-pri-zdravstveni-obravnavi-pacientov\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/"},{"@type":"ListItem","position":2,"name":"E-Naro\u010dilnica za podjetje &#8220;Napake pri zdravstveni obravnavi pacientov&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/#website","url":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/","name":"https:\/\/www.prosunt.si\/prosunt-2-2-2","description":"Usposabljanje varnost pacientov kakovost","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sl-SI"}]}},"_links":{"self":[{"href":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/wp-json\/wp\/v2\/pages\/2606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/wp-json\/wp\/v2\/comments?post=2606"}],"version-history":[{"count":0,"href":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/wp-json\/wp\/v2\/pages\/2606\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.prosunt.si\/prosunt-2-2-2\/wp-json\/wp\/v2\/media?parent=2606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}